{"id":56,"date":"2022-04-01T21:40:45","date_gmt":"2022-04-01T19:40:45","guid":{"rendered":"http:\/\/lodz2.grudnagorna.pl\/?page_id=56"},"modified":"2022-04-02T01:02:46","modified_gmt":"2022-04-01T23:02:46","slug":"kancelaria","status":"publish","type":"page","link":"https:\/\/michal.org.pl\/index.php\/kancelaria\/","title":{"rendered":"KANCELARIA"},"content":{"rendered":"<div class=\"kancelaria\">\nKANCELARIA PARAFIALNA<br \/>\nczynna<br \/>\nod poniedzia\u0142ku do pi\u0105tku<br \/>\n7:30-8:00, 16:30-17:30<\/div>\n","protected":false},"excerpt":{"rendered":"<p>KANCELARIA PARAFIALNA czynna od poniedzia\u0142ku do pi\u0105tku 7:30-8:00, 16:30-17:30<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-56","page","type-page","status-publish","hentry","post"],"_links":{"self":[{"href":"https:\/\/michal.org.pl\/index.php\/wp-json\/wp\/v2\/pages\/56","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/michal.org.pl\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/michal.org.pl\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/michal.org.pl\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/michal.org.pl\/index.php\/wp-json\/wp\/v2\/comments?post=56"}],"version-history":[{"count":2,"href":"https:\/\/michal.org.pl\/index.php\/wp-json\/wp\/v2\/pages\/56\/revisions"}],"predecessor-version":[{"id":250,"href":"https:\/\/michal.org.pl\/index.php\/wp-json\/wp\/v2\/pages\/56\/revisions\/250"}],"wp:attachment":[{"href":"https:\/\/michal.org.pl\/index.php\/wp-json\/wp\/v2\/media?parent=56"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}